{"id":14898,"date":"2023-07-13T15:08:04","date_gmt":"2023-07-13T13:08:04","guid":{"rendered":"https:\/\/poverso.com\/la-premiere-correction-de-sa-vie\/"},"modified":"2026-03-30T17:33:46","modified_gmt":"2026-03-30T15:33:46","slug":"la-premiere-elevage-de-votre-vie","status":"publish","type":"post","link":"https:\/\/poverso.com\/fr\/la-premiere-elevage-de-votre-vie\/BDSM-Spanking\/","title":{"rendered":"La (premi\u00e8re) correction de sa vie"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>J&rsquo;ai rencontr\u00e9 une femme qui voulait que je la punisse. Au d\u00e9part, il \u00e9tait pr\u00e9vu de lui donner 50 coups de poing sur ses fesses d\u00e9nud\u00e9es pour ne pas l&rsquo;avoir dit. En raison de quelques impertinences, 20 coups suppl\u00e9mentaires ont \u00e9t\u00e9 ajout\u00e9s, ce qui devait faire un total de 70 coups avec diff\u00e9rents instruments. Nous nous parlions d\u00e9j\u00e0 depuis un certain temps sur WhatsApp et nous nous \u00e9tions d\u00e9j\u00e0 dit beaucoup de choses, c&rsquo;est pourquoi nous nous faisions confiance.   <br\/><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda02979&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda02979\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/EVAs_leiden-scaled.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading Poverso_H2\" id=\"h-davor\">Avant cela :<\/h2>\n\n<p>Nous nous sommes d\u00e9clench\u00e9s mutuellement sur le chat avec nos fantasmes. Elle avait une relation ambivalente avec le nombre et la duret\u00e9 des coups. Cela me poussait \u00e0 placer la barre toujours plus haut. Sa peur, mais aussi le fait qu&rsquo;elle comprenne qu&rsquo;elle en avait besoin ou qu&rsquo;elle le m\u00e9ritait, m&rsquo;excitaient \u00e9norm\u00e9ment et j&rsquo;admirais cette femme. Elle aussi \u00e9tait excit\u00e9e par nos conversations honn\u00eates, ce qui lui a valu quelques nuits tr\u00e8s agit\u00e9es.    <br\/><br\/>Comme elle craignait de ne pas pouvoir supporter la douleur, je devais l&rsquo;attacher et la b\u00e2illonner. Cela m&rsquo;a procur\u00e9 un plaisir fou. J&rsquo;\u00e9tais impatient d&rsquo;avoir ses fesses devant moi.  <br\/><br\/>Comme nous devions nous rencontrer un dimanche, je lui avais encore fait tr\u00e8s peur le jeudi. Je pouvais voir \u00e0 son style d&rsquo;\u00e9criture qu&rsquo;elle avait vraiment tr\u00e8s peur maintenant. Je commen\u00e7ais \u00e0 craindre qu&rsquo;elle ne fasse faux bond. Peu de temps apr\u00e8s, elle a \u00e9crit cette phrase m\u00e9morable : \u00ab\u00a0<strong>Demain, ce n&rsquo;est que vendredi<\/strong>\u00a0\u00bb et j&rsquo;ai compris qu&rsquo;elle \u00e9tait impatiente de nous rencontrer, malgr\u00e9 ses inqui\u00e9tudes.   <br\/><br\/>Gr\u00e2ce \u00e0 nos d\u00e9clenchements mutuels et \u00e0 nos mont\u00e9es en puissance dans le chat, elle m&rsquo;a r\u00e9v\u00e9l\u00e9 quelques autres manquements, ce qui m&rsquo;a in\u00e9vitablement oblig\u00e9 \u00e0 augmenter la sanction. Elle a donc re\u00e7u la sanction susmentionn\u00e9e deux fois ce jour-l\u00e0, avec une longue pause entre les deux. <\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda02e04&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda02e04\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/Elbe-Blankenese-Strand_0332-1536x981-1-1024x654.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Si elle se montrait insolente pendant la pause, elle recevrait en cours de route (\u00e0 l&rsquo;ext\u00e9rieur) un autre 50 avec cinq cannes fra\u00eechement cueillies. Il \u00e9tait pr\u00e9vu que nous allions ensemble \u00e0 l&rsquo;Elbe. <\/p>\n<\/div>\n<\/div>\n\n<p>Elle m&rsquo;a assur\u00e9 \u00e0 plusieurs reprises qu&rsquo;elle avait m\u00e9rit\u00e9 cette correction. Elle a \u00e9galement reconnu que la deuxi\u00e8me punition devait \u00eatre plus s\u00e9v\u00e8re. <\/p>\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading Poverso_H2\" id=\"h-das-treffen\">La r\u00e9union :<\/h2>\n\n<p>Nous nous sommes rencontr\u00e9s pr\u00e8s de chez moi, sans engagement, pour faire connaissance et voir si nous \u00e9tions compatibles. Cela correspondait et nous sommes all\u00e9s chez moi. Elle savait que d\u00e8s que nous arrivions au \u00ab\u00a0lieu de punition\u00a0\u00bb, ses fesses devaient \u00eatre accessibles pour moi \u00e0 tout moment. J&rsquo;ai toujours une cravache avec moi et si elle commet une faute, elle la ressent imm\u00e9diatement sur ses fesses. Elle portait une robe et rien en dessous, ce qui \u00e9tait bien. Par la suite, je me suis rendu compte que j&rsquo;\u00e9tais plus excit\u00e9 de ne pas l&rsquo;avoir nue devant moi, mais de lui remonter sa robe et de la ch\u00e2tier ensuite.     <\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Une image avec des instructions et des positions que je lui avais envoy\u00e9e pr\u00e9c\u00e9demment s&rsquo;est affich\u00e9e devant elle sur un \u00e9cran. Malheureusement, je n&rsquo;avais que des images de femmes ayant d\u00e9j\u00e0 des marques sur les fesses. <\/p>\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda033d8&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda033d8\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/Allgemein-Strafen-1024x697.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n<p><br\/>Nous avons mang\u00e9 la meilleure tarte aux fraises de la ville et bu un cappuccino. Nous avons parl\u00e9 pendant un bon moment et avons ri ensemble. Pour moi, c&rsquo;\u00e9tait tr\u00e8s d\u00e9tendu, m\u00eame si - comme toujours avec une nouvelle femme ou une nouvelle session - j&rsquo;\u00e9tais tr\u00e8s excit\u00e9. Heureusement, je n&rsquo;ai pas perdu cela. Pour elle, ce n&rsquo;\u00e9tait pas aussi relaxant, car elle voyait tout le temps mes divers instruments de ch\u00e2timent et la table sur laquelle elle allait \u00eatre fix\u00e9e. \u00c0 c\u00f4t\u00e9 d&rsquo;elle, les instruments avec lesquels elle allait \u00eatre ch\u00e2ti\u00e9e aujourd&rsquo;hui \u00e9taient encore bien align\u00e9s.     <\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda03658&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda03658\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/2023-05-13 12_07_14-SadoMaso-Chat &#x2013; Opera.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda03851&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda03851\" class=\"aligncenter size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/Mit-Guertel_Cartoon.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Malheureusement, j&rsquo;avais oubli\u00e9 d&rsquo;\u00e9teindre mon deuxi\u00e8me \u00e9cran, sur lequel \u00e9taient affich\u00e9es mes photos pr\u00e9f\u00e9r\u00e9es. Il est possible que cela ne vous ait pas plu, car je m&rsquo;appr\u00eate \u00e0 les mettre sur la table et \u00e0 leur donner une racl\u00e9e. <\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda03b16&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda03b16\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/sklavinhalter_1964_1-2.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n<\/div>\n\n<p>Puis les choses sont devenues s\u00e9rieuses et j&rsquo;ai \u00e9num\u00e9r\u00e9 les raisons pour lesquelles elle devait \u00eatre punie et le nombre de coups qu&rsquo;elle allait recevoir sur ses fesses nues. Je n&rsquo;ai pas eu \u00e0 lui expliquer les instruments, car elle les avait vus depuis le d\u00e9but. Elle avait apport\u00e9 un autre cadeau avec lequel elle voulait sans doute me rendre un peu plus charitable. Elle m&rsquo;a demand\u00e9 de ne pas utiliser une claque particuli\u00e8re. Je lui ai demand\u00e9 si elle l&rsquo;avait d\u00e9j\u00e0 test\u00e9e. Comme ce n&rsquo;\u00e9tait pas le cas, j&rsquo;ai imm\u00e9diatement fait un test sur ses fesses pleines d&rsquo;espoir.     <\/p>\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda03e58&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda03e58\" class=\"alignright size-large is-resized wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/Evas-Strafplatz.jpg\" alt=\"\" style=\"width:156px;height:125px\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n<p>Elle a \u00e9t\u00e9 attach\u00e9e et b\u00e2illonn\u00e9e et a re\u00e7u sa premi\u00e8re fess\u00e9e. Apr\u00e8s chaque 20e coup, je calmais ses fesses. Apr\u00e8s la punition, je lui ai demand\u00e9 quels instruments elle pr\u00e9f\u00e9rait (th\u00e8me de la \u00ab\u00a0belle douleur\u00a0\u00bb et de la \u00ab\u00a0mauvaise douleur\u00a0\u00bb).  <br\/><br\/>Elle ne le savait pas vraiment, c&rsquo;est pourquoi elle en a eu cinq de plus, voire plus, \u00e0 chaque instrument, juste pour s&rsquo;assurer que ses indications \u00e9taient solides. Ensuite, j&rsquo;ai soign\u00e9 ses fesses, que j&rsquo;aimais beaucoup mieux maintenant avec les marques, et je lui ai donn\u00e9 un peu de temps pour elle. <br\/><br\/>Pendant la pause, je lui ai fait visiter Hambourg et nous sommes pass\u00e9es par la boutique Bizarre pour faire un peu de shopping. Sur place, nous avons test\u00e9 quelques cannes sur ses fesses. <\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda040ba&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda040ba\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/boutique-bizarre-eingangsbereich-1.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda042ee&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda042ee\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/boutique-bizarre-schuhe-1024x674.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda044a5&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda044a5\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/fetisch-masken.jpg\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div>\n<\/div>\n\n<p>Nous avons eu de superbes discussions et avons beaucoup ri ensemble. Bon, la bastonnade prophylactique en plein air n&rsquo;a pas eu lieu sur l&rsquo;Elbe. Il y avait trop de monde. Je l&rsquo;ai punie de 50 coups, mais malheureusement pas avec des cannes neuves. Elle avait remarqu\u00e9 avec l\u00e9g\u00e8ret\u00e9 que la premi\u00e8re punition n&rsquo;avait pas \u00e9t\u00e9 assez s\u00e9v\u00e8re et durable, c&rsquo;est-\u00e0-dire comme elle l&rsquo;avait imagin\u00e9.    <br\/><\/p>\n\n<p><br\/>Comme la premi\u00e8re s\u00e9ance avait \u00e9t\u00e9 plut\u00f4t amusante pour elle, je voulais qu&rsquo;elle en prenne pour son grade. Sa r\u00e9action \u00e0 mes coups m&rsquo;a tellement excit\u00e9 que j&rsquo;ai eu envie de lui donner une bonne fess\u00e9e. <br\/><br\/>Comme je ne l&rsquo;avais plus attach\u00e9e ni b\u00e2illonn\u00e9e - elle avait accept\u00e9 humblement sa correction et ses g\u00e9missements \u00e0 chaque coup m&rsquo;avaient beaucoup excit\u00e9 - elle essayait maintenant de d\u00e9tourner ses fesses. Mais le b\u00e2ton suivait inexorablement ses joues rouge vif.<br\/>Elle a fini par y renoncer et s&rsquo;est tue. On n&rsquo;entendait plus que le claquement du paddle que j&rsquo;utilisais maintenant sur ses joues. Ma r\u00e9action m&rsquo;a donn\u00e9 l&rsquo;occasion, consciente ou non, de lui donner des coups. Elle ne l&rsquo;aurait jamais permis si elle ne l&rsquo;avait pas voulu, car c&rsquo;est une femme tr\u00e8s s\u00fbre d&rsquo;elle et heureusement non soumise.    <br\/><\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda04821&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda04821\" class=\"alignright size-large is-resized wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/Badebuertse_frei.gif\" alt=\"\" style=\"width:150px;height:135px\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Finalement, elle l&rsquo;a eu avec la brosse de bain sur ses fesses nues et un premier succ\u00e8s de la correction et de l&rsquo;\u00e9ducation est apparu, en ce sens qu&rsquo;elle a \u00e9t\u00e9 ramen\u00e9e un peu brutalement \u00e0 la r\u00e9alit\u00e9 et a dit d\u00e9votement : \u00ab\u00a0<em>Je n&rsquo;en peux plus<\/em>\u00ab\u00a0<em>.<\/em><br\/><\/p>\n<\/div>\n<\/div>\n\n<p><strong>Au total, elle a re\u00e7u plus de 300 coups de fouet sur ses fesses nues.<\/strong><\/p>\n\n<p><br\/>Elle a \u00e9galement re\u00e7u des photos de ses fesses (avant\/apr\u00e8s) ainsi qu&rsquo;une vid\u00e9o de rappel. Je lui ai conseill\u00e9 de regarder cette vid\u00e9o tous les matins pour qu&rsquo;elle se souvienne de ce qui l&rsquo;attendait si elle ne suivait pas le chemin que j&rsquo;avais trac\u00e9 pour elle. <\/p>\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04ccda04c3b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04ccda04c3b\" class=\"wp-block-image size-large wp-lightbox-container\"><img decoding=\"async\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/poverso.com\/Medien\/Webseite\/Beitr&#xE4;ge\/Der-rote-1.png\" alt=\"\"\/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Agrandir\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n<p>Lorsqu&rsquo;elle est partie, elle a re\u00e7u 15 coups de poing de la part d&rsquo;un rouge fin et m\u00e9chant qui lui a servi d&rsquo;aide-m\u00e9moire. Ainsi, elle \u00e9tait assur\u00e9e de penser tr\u00e8s fort \u00e0 la <strong>fess\u00e9e de sa vie<\/strong> sur le chemin du retour. <\/p>\n\n<div style=\"height:19px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading Poverso_H3\" id=\"h-die-zeit-danach\">Le temps d&rsquo;apr\u00e8s :<\/h3>\n\n<p>Le lendemain, elle m&rsquo;a \u00e9crit : \u00ab\u00a0J&rsquo;ai tr\u00e8s mal quand je suis assise, ce qui m&rsquo;excite. Quand je suis allong\u00e9e sur le ventre, je pourrais d\u00e9j\u00e0 \u00eatre devant toi et j&rsquo;aimerais revivre ce que j&rsquo;ai v\u00e9cu hier\u00a0\u00bb. Moi aussi, j&rsquo;\u00e9tais encore tellement excit\u00e9 que je voulais recommencer imm\u00e9diatement. <\/p>\n\n<p>Ses fesses lui ont fait mal pendant pr\u00e8s d&rsquo;une semaine lorsqu&rsquo;elle \u00e9tait assise. Mais chaque fois que la douleur commen\u00e7ait, cela l&rsquo;excitait. Apr\u00e8s un certain temps, nous \u00e9tions tous les deux incroyablement d\u00e9tendus. Comme nous avions tous les deux vol\u00e9 et obtenu quelque chose que nous recherchions consciemment ou inconsciemment depuis longtemps, nous \u00e9tions vraiment rassasi\u00e9s pour commencer.   <\/p>\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading Poverso_H3\" id=\"h-die-zukunft\">L&rsquo;avenir :<\/h3>\n\n<p>Bien s\u00fbr, ce n&rsquo;est pas certain, car nous habitons un peu plus loin. Mais elle a compris que les bons conseils ou les couchers sur les genoux n&rsquo;ont aucun effet sur elle, et que seule la fess\u00e9e s\u00e9v\u00e8re est prometteuse. A l&rsquo;avenir, elle sera donc r\u00e9guli\u00e8rement ch\u00e2ti\u00e9e une fois par mois. Elle dispose d&rsquo;un catalogue de punitions. Elle suit \u00e9galement une formation de motivation afin de ne pas n\u00e9gliger ses activit\u00e9s sportives.    <\/p>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity hr-blog\"\/>\n\n<p class=\"has-text-align-center gewaehr has-black-background-color has-background\" style=\"font-size:18px\">O\u00f9 puis-je en faire l&rsquo;exp\u00e9rience ? <span class=\"popup-trigger popmake-11184\" data-popup-id=\"11184\" data-do-default=\"0\"><strong>Info &amp; Clause de non-responsabilit\u00e9 !<\/strong><\/span><\/p>\n\n<div class=\"wp-block-columns Wo_erleben has-black-background-color has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<h1 class=\"wp-block-heading has-text-align-left Poverso_H1 has-large-font-size\"><strong>O\u00f9 puis-je<\/strong><\/h1>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-left Poverso_H1 has-large-font-size\"><strong>l&rsquo;exp\u00e9rience<\/strong><\/h1>\n\n\n\n<div style=\"height:8px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center sucht has-white-color has-vivid-red-background-color has-text-color has-background has-link-color wp-elements-6904c00b8d14183804908ef52f674434\" style=\"font-size:24px\">Elle cherche LUI<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/poverso.com\/Medien\/Vorlagen\/Knallroter-Po-mit-Rohrstock-in-der-Hand.jpg\" alt=\"BDSM &amp;amp; Spanking : une femme avec un derri&#xE8;re rouge vif et une canne &#xE0; la main\"\/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column Wo_erleben_rechts is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading Poverso_H2\" id=\"h-po-versohlen\"><br\/><a href=\"https:\/\/poverso.com\/fr\/\" title=\"Link : Site web de Poverso\">Fess\u00e9e<\/a><\/h3>\n\n\n\n<p>La fess\u00e9e pour r\u00e9aliser les d\u00e9sirs et les fantasmes <strong>SM<\/strong>. <br\/>- P\u00e9nitencier de la vieille \u00e9cole<br\/>- Pr\u00e9paration professionnelle de la douleur<br\/>- Centre de r\u00e9\u00e9ducation selon les normes<br\/>- Traitement \u00e0 long terme avec garantie de succ\u00e8s<br\/>- Ch\u00e2timents &amp; acuPOture sur les fesses nues<br\/>- Zones de ch\u00e2timents au choix, sur demande<br\/>- Traitements \u00e0 l&rsquo;\u00e9lectricit\u00e9 et \u00e0 l&rsquo;aiguille possibles<br\/>- Visites en ext\u00e9rieur ou \u00e0 domicile sur demande<br\/>- Soin de la peau du corps entier avec des orties<br\/>- Aftercare inclus dans tous les traitements<br\/>- Services g\u00e9n\u00e9ralement gratuits<\/p>\n\n\n\n<p class=\"Poverso_H3 popmake-11516\" style=\"text-decoration:underline\">Nos instruments d&rsquo;\u00e9levage<\/p>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p style=\"text-decoration:underline\" class=\"popmake-11494\"><\/p>\n<\/div>\n<\/div>\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-medium-font-size\">Jeu de r\u00f4le : <a href=\"https:\/\/poverso.com\/fr\/jeux-de-role-taches-general\/\">Jeux de r\u00f4le<\/a><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Infos (th\u00e8me) : <a href=\"https:\/\/poverso.com\/fr\/jaime-avoir-mal\/\">J&rsquo;aime la douleur<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-medium-font-size\">Attention : <a href=\"https:\/\/poverso.com\/fr\/avant-pendant-apres-aftercare\/\">Aftercare<\/a> \/ <a href=\"https:\/\/poverso.com\/fr\/lecon-de-vol-bdsm\/\">Heure de vol<\/a><\/p>\n\n\n\n<p class=\"has-medium-font-size\">Conseils : <a href=\"https:\/\/poverso.com\/fr\/outil-client-sm-sexe\/\">Outils<\/a> \/ <a href=\"https:\/\/poverso.com\/fr\/technique-de-frappe-positions-sm\/\">Technique de frappe<\/a><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>De la fess\u00e9e \u00e9rotique avec quelques tapes sur les fesses au ch\u00e2timent s\u00e9v\u00e8re et implacable avec la canne, le fouet et la brosse de bain, jusqu&rsquo;\u00e0 la mouche.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[95],"tags":[116,126,441],"class_list":["post-14898","post","type-post","status-publish","format-standard","hentry","category-berichte","tag-fessee","tag-punition","tag-xxx"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/poverso.com\/fr\/wp-json\/wp\/v2\/posts\/14898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poverso.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/poverso.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/poverso.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/poverso.com\/fr\/wp-json\/wp\/v2\/comments?post=14898"}],"version-history":[{"count":1,"href":"https:\/\/poverso.com\/fr\/wp-json\/wp\/v2\/posts\/14898\/revisions"}],"predecessor-version":[{"id":46136,"href":"https:\/\/poverso.com\/fr\/wp-json\/wp\/v2\/posts\/14898\/revisions\/46136"}],"wp:attachment":[{"href":"https:\/\/poverso.com\/fr\/wp-json\/wp\/v2\/media?parent=14898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/poverso.com\/fr\/wp-json\/wp\/v2\/categories?post=14898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/poverso.com\/fr\/wp-json\/wp\/v2\/tags?post=14898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}